{"id":7354,"date":"2022-01-08T22:50:54","date_gmt":"2022-01-08T21:50:54","guid":{"rendered":"http:\/\/trlika.com\/?post_type=jetpack-testimonial&#038;p=7354"},"modified":"2022-01-08T22:50:54","modified_gmt":"2022-01-08T21:50:54","slug":"jennifer-gros-de","status":"publish","type":"jetpack-testimonial","link":"http:\/\/trlika.com\/de\/testimonial\/jennifer-gros-de\/","title":{"rendered":"Jennifer Gro\u00df, De"},"content":{"rendered":"<p>Super Gastgeber. Die Ferienwohnung ist super f\u00fcr eine Kleine Familie wir waren dort mit unseren 2 Kindern und es war vom Platz super und sauber.Die Gastgeber sind sehr Herzlich und k\u00fcmmern sich auch bei Nachfrage direkt falls einem was fehlt ect. Wir waren sehr gerne dort und kommen sehr gerne wieder. \ud83d\ude0a\ud83d\ude0e<\/p>\n\n\n\n<p><span class=\"has-inline-color has-primary-color\"><a href=\"http:\/\/trlika.com\/de\/apartments-mikelic\/\" data-type=\"URL\" data-id=\"http:\/\/trlika.com\/apartments-mikelic\/\" target=\"_blank\" rel=\"noreferrer noopener\">For House Mikelic Zdenka and Ivan<\/a><\/span><\/p>\n\n\n\n<p><a href=\"https:\/\/goo.gl\/maps\/TXJvkF44WZaz2Mdg7\" data-type=\"URL\" data-id=\"https:\/\/goo.gl\/maps\/TXJvkF44WZaz2Mdg7\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Super Gastgeber. Die Ferienwohnung ist super f\u00fcr eine Kleine Familie wir waren dort mit unseren 2 Kindern und es war vom Platz super und sauber.Die Gastgeber sind sehr Herzlich und k\u00fcmmern sich auch bei Nachfrage direkt falls einem was fehlt ect. Wir waren sehr gerne dort und kommen sehr gerne wieder. \ud83d\ude0a\ud83d\ude0e For House Mikelic &hellip; <a href=\"http:\/\/trlika.com\/de\/testimonial\/jennifer-gros-de\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Jennifer Gro\u00df, De&#8221;<\/span><\/a><\/p>","protected":false},"featured_media":0,"menu_order":0,"template":"","class_list":["post-7354","jetpack-testimonial","type-jetpack-testimonial","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":665,"url":"http:\/\/trlika.com\/de\/testimonial\/marcella\/","url_meta":{"origin":7354,"position":0},"title":"Marcella, NT","author":"Ivica Mikeli\u0107","date":"22. M\u00e4rz 2020.","format":false,"excerpt":"Absolut sch\u00f6ner Aufenthalt. Wirklich komfortable Wohnung mit allem, was Sie brauchen. Der Gastgeber ist sehr entgegenkommend und super freundlich! Auch die Lage auf der Insel ist gro\u00dfartig.","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13241,"url":"http:\/\/trlika.com\/de\/testimonial\/christoph-natalie\/","url_meta":{"origin":7354,"position":1},"title":"Christoph &amp; Natalie\u00a0","author":"Ivica Mikeli\u0107","date":"5. Februar 2024.","format":false,"excerpt":"We can totally recommend to stay at Ivica\u2019s place! You can see how much love is put in every detail. The view from the terrace is amazing, the kitchen very well equipped, fast internet, cozy couch, super comfortable bed, just everything was perfect from the beginning.....","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/trlika.com\/de\/wp-json\/wp\/v2\/jetpack-testimonial\/7354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/trlika.com\/de\/wp-json\/wp\/v2\/jetpack-testimonial"}],"about":[{"href":"http:\/\/trlika.com\/de\/wp-json\/wp\/v2\/types\/jetpack-testimonial"}],"version-history":[{"count":1,"href":"http:\/\/trlika.com\/de\/wp-json\/wp\/v2\/jetpack-testimonial\/7354\/revisions"}],"predecessor-version":[{"id":7355,"href":"http:\/\/trlika.com\/de\/wp-json\/wp\/v2\/jetpack-testimonial\/7354\/revisions\/7355"}],"wp:attachment":[{"href":"http:\/\/trlika.com\/de\/wp-json\/wp\/v2\/media?parent=7354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}